{"id":819,"date":"2024-05-21T15:15:54","date_gmt":"2024-05-21T13:15:54","guid":{"rendered":"https:\/\/unitrust-zrt.hu\/?p=819"},"modified":"2024-05-21T15:15:54","modified_gmt":"2024-05-21T13:15:54","slug":"semcorp-debrecen-2","status":"publish","type":"post","link":"https:\/\/unitrust.hu\/en\/referencia\/semcorp-debrecen-2\/","title":{"rendered":"SEMCORP Debrecen"},"content":{"rendered":"<p>Lithium - Ion battery separator foil - factory technological engineering design in cooperation with Olp-Tech Ltd.<\/p>","protected":false},"excerpt":{"rendered":"<p>Lithium - Ion battery separator foil - factory technological engineering design in cooperation with Olp-Tech Ltd.<\/p>","protected":false},"author":1,"featured_media":823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23],"tags":[],"class_list":["post-819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ipari-projektek"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SEMCORP Debrecen - Unitrust Zrt.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unitrust.hu\/en\/referencia\/semcorp-debrecen-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEMCORP Debrecen - Unitrust Zrt.\" \/>\n<meta property=\"og:description\" content=\"L\u00edtium &#8211; Ion akkumul\u00e1tor elv\u00e1laszt\u00f3f\u00f3lia &#8211; gy\u00e1rban technol\u00f3giai g\u00e9p\u00e9szeti kivitelez\u00e9s az Olp-Tech Kft.-vel k\u00f6z\u00f6sen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unitrust.hu\/en\/referencia\/semcorp-debrecen-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Unitrust Zrt.\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T13:15:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"pixelworks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pixelworks\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/\"},\"author\":{\"name\":\"pixelworks\",\"@id\":\"https:\/\/unitrust.hu\/en\/#\/schema\/person\/51c48cd58713ef72b814170e2e774ce1\"},\"headline\":\"SEMCORP Debrecen\",\"datePublished\":\"2024-05-21T13:15:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/\"},\"wordCount\":29,\"publisher\":{\"@id\":\"https:\/\/unitrust.hu\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp\",\"articleSection\":[\"Ipari projektek\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/\",\"url\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/\",\"name\":\"SEMCORP Debrecen - Unitrust Zrt.\",\"isPartOf\":{\"@id\":\"https:\/\/unitrust.hu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp\",\"datePublished\":\"2024-05-21T13:15:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage\",\"url\":\"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp\",\"contentUrl\":\"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp\",\"width\":1200,\"height\":628,\"caption\":\"semcorp debrecen 2 010\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\/\/unitrust.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEMCORP Debrecen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unitrust.hu\/en\/#website\",\"url\":\"https:\/\/unitrust.hu\/en\/\",\"name\":\"Unitrust Zrt.\",\"description\":\"Magas- \u00e9s m\u00e9ly\u00e9p\u00edt\u00e9si l\u00e9tes\u00edtm\u00e9nyek, \u00e9p\u00fcletg\u00e9p\u00e9szeti rendszerek tervez\u00e9se, kivitelez\u00e9se, \u00fczemeltet\u00e9se.\",\"publisher\":{\"@id\":\"https:\/\/unitrust.hu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unitrust.hu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/unitrust.hu\/en\/#organization\",\"name\":\"Unitrust Zrt.\",\"url\":\"https:\/\/unitrust.hu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/unitrust.hu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/04\/unitrust-zrt-logo-white-001.svg\",\"contentUrl\":\"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/04\/unitrust-zrt-logo-white-001.svg\",\"width\":147,\"height\":115,\"caption\":\"Unitrust Zrt.\"},\"image\":{\"@id\":\"https:\/\/unitrust.hu\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/unitrust.hu\/en\/#\/schema\/person\/51c48cd58713ef72b814170e2e774ce1\",\"name\":\"pixelworks\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/unitrust.hu\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a04d762ef3af423451aa40a8594ca1a55757e1965edfe2169e8d35f6dd3c162?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a04d762ef3af423451aa40a8594ca1a55757e1965edfe2169e8d35f6dd3c162?s=96&d=mm&r=g\",\"caption\":\"pixelworks\"},\"sameAs\":[\"https:\/\/unitrust.hu\"],\"url\":\"https:\/\/unitrust.hu\/en\/referencia\/author\/pixelworks\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEMCORP Debrecen - Unitrust Zrt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unitrust.hu\/en\/referencia\/semcorp-debrecen-2\/","og_locale":"en_GB","og_type":"article","og_title":"SEMCORP Debrecen - Unitrust Zrt.","og_description":"L\u00edtium &#8211; Ion akkumul\u00e1tor elv\u00e1laszt\u00f3f\u00f3lia &#8211; gy\u00e1rban technol\u00f3giai g\u00e9p\u00e9szeti kivitelez\u00e9s az Olp-Tech Kft.-vel k\u00f6z\u00f6sen.","og_url":"https:\/\/unitrust.hu\/en\/referencia\/semcorp-debrecen-2\/","og_site_name":"Unitrust Zrt.","article_published_time":"2024-05-21T13:15:54+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp","type":"image\/webp"}],"author":"pixelworks","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pixelworks"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#article","isPartOf":{"@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/"},"author":{"name":"pixelworks","@id":"https:\/\/unitrust.hu\/en\/#\/schema\/person\/51c48cd58713ef72b814170e2e774ce1"},"headline":"SEMCORP Debrecen","datePublished":"2024-05-21T13:15:54+00:00","mainEntityOfPage":{"@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/"},"wordCount":29,"publisher":{"@id":"https:\/\/unitrust.hu\/en\/#organization"},"image":{"@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage"},"thumbnailUrl":"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp","articleSection":["Ipari projektek"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/","url":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/","name":"SEMCORP Debrecen - Unitrust Zrt.","isPartOf":{"@id":"https:\/\/unitrust.hu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage"},"image":{"@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage"},"thumbnailUrl":"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp","datePublished":"2024-05-21T13:15:54+00:00","breadcrumb":{"@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#primaryimage","url":"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp","contentUrl":"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/05\/semcorp-debrecen-2-010.webp","width":1200,"height":628,"caption":"semcorp debrecen 2 010"},{"@type":"BreadcrumbList","@id":"https:\/\/unitrust.hu\/referencia\/semcorp-debrecen-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/unitrust.hu\/"},{"@type":"ListItem","position":2,"name":"SEMCORP Debrecen"}]},{"@type":"WebSite","@id":"https:\/\/unitrust.hu\/en\/#website","url":"https:\/\/unitrust.hu\/en\/","name":"Unitrust Zrt.","description":"Magas- \u00e9s m\u00e9ly\u00e9p\u00edt\u00e9si l\u00e9tes\u00edtm\u00e9nyek, \u00e9p\u00fcletg\u00e9p\u00e9szeti rendszerek tervez\u00e9se, kivitelez\u00e9se, \u00fczemeltet\u00e9se.","publisher":{"@id":"https:\/\/unitrust.hu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unitrust.hu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/unitrust.hu\/en\/#organization","name":"Unitrust Zrt.","url":"https:\/\/unitrust.hu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/unitrust.hu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/04\/unitrust-zrt-logo-white-001.svg","contentUrl":"https:\/\/unitrust.hu\/wp-content\/uploads\/2024\/04\/unitrust-zrt-logo-white-001.svg","width":147,"height":115,"caption":"Unitrust Zrt."},"image":{"@id":"https:\/\/unitrust.hu\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/unitrust.hu\/en\/#\/schema\/person\/51c48cd58713ef72b814170e2e774ce1","name":"pixelworks","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/unitrust.hu\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a04d762ef3af423451aa40a8594ca1a55757e1965edfe2169e8d35f6dd3c162?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a04d762ef3af423451aa40a8594ca1a55757e1965edfe2169e8d35f6dd3c162?s=96&d=mm&r=g","caption":"pixelworks"},"sameAs":["https:\/\/unitrust.hu"],"url":"https:\/\/unitrust.hu\/en\/referencia\/author\/pixelworks\/"}]}},"_links":{"self":[{"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/posts\/819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":0,"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/media\/823"}],"wp:attachment":[{"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unitrust.hu\/en\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}